{"id":6160,"date":"2025-02-24T02:23:33","date_gmt":"2025-02-24T01:23:33","guid":{"rendered":"https:\/\/susannealbers.de\/blog\/?p=6160"},"modified":"2025-02-24T02:23:33","modified_gmt":"2025-02-24T01:23:33","slug":"schwarzblau-ist-die-haselnuss","status":"publish","type":"post","link":"https:\/\/susannealbers.de\/blog\/2025\/02\/24\/schwarzblau-ist-die-haselnuss\/","title":{"rendered":"Schwarzblau ist die Haselnuss"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Schwarzblau ist die Haselnuss (Satire) - music by Susanne\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/Ba3l_K_yO9o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>Strophe<br>Schwarzblau ist die Haselnuss,<br>Schwarzblau unser Vaterland.<br>Schleichend wird das Volk verf\u00fchrt,<br>Demokratie? Bald abgebrannt.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Refrain<br>Hei ho, schwarzblau regiert,<br>Wer nicht jubelt, der verliert.<br>Mitte wankt, nach rechts sie zieht,<br>Bis am Ende nichts mehr bl\u00fcht.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li>Strophe<br>B\u00fcrgerlich mit feinem Kleid,<br>Doch im Keller lagert Braun.<br>Wer zu laut den Wind bemerkt,<br>Der kriegt&#8217;s Maul gestopft \u2013 mit Zaun.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Refrain<br>Hei ho, schwarzblau regiert,<br>Wer nicht jubelt, der verliert.<br>Mitte wankt, nach rechts sie zieht,<br>Bis am Ende nichts mehr bl\u00fcht.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\"><li>Strophe<br>Rettet Deutschland, ruft der Chor,<br>Und die Mehrheit klatscht im Takt.<br>Sp\u00e4ter fragt man voller Scham,<br>Warum hab&#8217;n wir nichts gesagt?<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Refrain<br>Hei ho, schwarzblau regiert,<br>Wer nicht jubelt, der verliert.<br>Mitte wankt, nach rechts sie zieht,<br>Bis am Ende nichts mehr bl\u00fcht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>StropheSchwarzblau ist die Haselnuss,Schwarzblau unser Vaterland.Schleichend wird das Volk verf\u00fchrt,Demokratie? Bald abgebrannt. RefrainHei ho, schwarzblau regiert,Wer nicht jubelt, der verliert.Mitte wankt, nach rechts sie zieht,Bis am Ende nichts mehr bl\u00fcht. StropheB\u00fcrgerlich mit feinem Kleid,Doch im Keller lagert Braun.Wer zu laut den Wind bemerkt,Der kriegt&#8217;s Maul gestopft \u2013 mit Zaun. RefrainHei ho, schwarzblau regiert,Wer nicht jubelt, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/susannealbers.de\/blog\/2025\/02\/24\/schwarzblau-ist-die-haselnuss\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Schwarzblau ist die Haselnuss&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3944,3942,3943],"class_list":["post-6160","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-3944","tag-bundestagswahl-2025","tag-wahl"],"_links":{"self":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts\/6160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/comments?post=6160"}],"version-history":[{"count":1,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts\/6160\/revisions"}],"predecessor-version":[{"id":6161,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts\/6160\/revisions\/6161"}],"wp:attachment":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/media?parent=6160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/categories?post=6160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/tags?post=6160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}