{"id":6125,"date":"2025-02-01T16:40:46","date_gmt":"2025-02-01T15:40:46","guid":{"rendered":"https:\/\/susannealbers.de\/blog\/?p=6125"},"modified":"2025-02-01T16:40:46","modified_gmt":"2025-02-01T15:40:46","slug":"softrock-oper-herz-des-universums-eine-mystische-einwohnung","status":"publish","type":"post","link":"https:\/\/susannealbers.de\/blog\/2025\/02\/01\/softrock-oper-herz-des-universums-eine-mystische-einwohnung\/","title":{"rendered":"Softrock-Oper: \u201eHerz des Universums\u201c &#8211; Eine mystische Einwohnung"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Softrock-Oper: \u201eHerz des Universums\u201c - Eine mystische Einwohnung - gesamt - music by Susanne\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/YHEQHot_fCE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Softrock-Oper: \u201eHerz des Universums\u201c (Eine mystische Reise nach Teresa von \u00c1vila) von Susanne Albers <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Softrock-Oper erz\u00e4hlt die Entwicklung einer Seele auf ihrem Weg zu Gott \u2013 von der ersten Sehnsucht bis zur v\u00f6lligen Einheit. Inspiriert von Teresa von \u00c1vilas mystischen Erfahrungen, f\u00fchrt sie den H\u00f6rer durch die wichtigsten Phasen der Gottesbegegnung. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd39 Musikalisch verbindet sie gef\u00fchlvolle, sehnsuchtsvolle Melodien mit kraftvollen Rock-Momenten, sanften Passagen der Hingabe und erhabenen Hymnen der Einheit. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd39 Lyrisch folgt sie Teresas mystischen Erlebnissen und Gedanken, \u00fcbersetzt in eine moderne, poetische Sprache. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd39 Spirituell ist sie ein Klangbild der inneren Reise \u2013 von der Unruhe \u00fcber die Ekstase bis zur endg\u00fcltigen Wandlung. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dramaturgischer Ablauf der Oper: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Intro <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=0s\">0:00<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1\ufe0f\u20e3 Ruf aus der Tiefe \u2013 Die Seele ruft nach Gott, sp\u00fcrt eine tiefe Leere und wei\u00df, dass nichts auf dieser Welt sie erf\u00fcllen kann. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=6s\">0:06<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2\ufe0f\u20e3 Die Wand f\u00e4llt \u2013 Pl\u00f6tzlich wird Gott nicht mehr nur erahnt, sondern als wirklich gegenw\u00e4rtig erlebt. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=220s\">3:40<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3\ufe0f\u20e3 G\u00f6ttliches Feuer \u2013 In einem ekstatischen Moment wird die Seele von der g\u00f6ttlichen Liebe \u00fcberw\u00e4ltigt und hinausgerissen. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=442s\">7:22<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4\ufe0f\u20e3 Frei von der Welt \u2013 Die Seele erkennt, dass weltliche Dinge sie nicht mehr binden \u2013 sie beginnt, alles loszulassen. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=661s\">11:01<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5\ufe0f\u20e3 Geschehen lassen \u2013 Sie versteht, dass sie nicht selbst handeln muss \u2013 Gott wirkt in ihr. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=887s\">14:47<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6\ufe0f\u20e3 Eins mit dem Ewigen \u2013 Ihr Wille, ihr Denken, ihr ganzes Sein verschmelzen mit Gottes Wirken. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=1088s\">18:08<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7\ufe0f\u20e3 Was kein Wort beschreiben kann \u2013 Ein Blick hinter die Schleier der Welt, ein Wissen im Nichtwissen, eine direkte Erkenntnis der g\u00f6ttlichen Wahrheit. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=1277s\">21:17<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8\ufe0f\u20e3 Er in mir, ich in ihm \u2013 Die Seele begreift, dass Gott nicht fern ist \u2013 er wohnt in ihr, in ihrem Herzen. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=1462s\">24:22<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9\ufe0f\u20e3 Geistliche Verm\u00e4hlung \u2013 Nicht nur die Seele liebt Gott \u2013 Gott liebt die Seele als seine Braut und nimmt sie als Partner an. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=1666s\">27:46<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd1f Alles ist verwandelt \u2013 Die mystische Erfahrung bleibt nicht nur innerlich, sondern ver\u00e4ndert das gesamte Leben der Seele. <a href=\"https:\/\/www.youtube.com\/watch?v=YHEQHot_fCE&amp;t=1870s\">31:10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Softrock-Oper: \u201eHerz des Universums\u201c (Eine mystische Reise nach Teresa von \u00c1vila) von Susanne Albers Diese Softrock-Oper erz\u00e4hlt die Entwicklung einer Seele auf ihrem Weg zu Gott \u2013 von der ersten Sehnsucht bis zur v\u00f6lligen Einheit. Inspiriert von Teresa von \u00c1vilas mystischen Erfahrungen, f\u00fchrt sie den H\u00f6rer durch die wichtigsten Phasen der Gottesbegegnung. \ud83d\udd39 Musikalisch verbindet &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/susannealbers.de\/blog\/2025\/02\/01\/softrock-oper-herz-des-universums-eine-mystische-einwohnung\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Softrock-Oper: \u201eHerz des Universums\u201c &#8211; Eine mystische Einwohnung&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6125","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts\/6125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/comments?post=6125"}],"version-history":[{"count":1,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts\/6125\/revisions"}],"predecessor-version":[{"id":6126,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/posts\/6125\/revisions\/6126"}],"wp:attachment":[{"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/media?parent=6125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/categories?post=6125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/susannealbers.de\/blog\/wp-json\/wp\/v2\/tags?post=6125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}